{"id":41023,"date":"2024-01-04T16:06:09","date_gmt":"2024-01-04T16:06:09","guid":{"rendered":"https:\/\/siemid.com\/?post_type=product&#038;p=41023"},"modified":"2024-01-04T16:42:55","modified_gmt":"2024-01-04T16:42:55","slug":"headlight-bulb-for-2001-2007-chevrolet-silverado-1500-driver-or-passenger-side","status":"publish","type":"product","link":"https:\/\/siemid.com\/it\/prodotto\/headlight-bulb-for-2001-2007-chevrolet-silverado-1500-driver-or-passenger-side\/","title":{"rendered":"Lampadina per fari per 2001-2007 Chevrolet Silverado 1500 lato conducente o passeggero"},"content":{"rendered":"<p>Nome_prodotto<\/br>Lampadina del faro<\/br><\/br>Montaggio<\/br>Si prega di controllare il filtro di montaggio per autoveicoli e la descrizione per vedere se questo articolo funziona sul vostro veicolo prima dell'acquisto!<\/br><\/br>Condizione<\/br>100% Nuovo in confezione di fabbrica, mai usato o installato. Assicura la qualit\u00e0 e le prestazioni del prodotto.<\/br><\/br>Articolo_Offerto<\/br>Quantit\u00e0 venduta: Venduto singolarmente<\/br><\/br>Nota<\/br>Singolo filamento C-8 per gli anabbaglianti<\/br><\/br>Posizione<\/br>Posizione: Lato destro o sinistro<\/br>Posizionamento sul veicolo: Sinistra, destra<\/br><\/br>Specifiche<\/br>Tipo di lampadina: Tipo di lampadina HB4<\/br><\/br>Numero_parte<\/br>14452297,9006ST<\/br><\/br>Garanzia<\/br>Garanzia del produttore: 1 anno di garanzia a chilometraggio illimitato<\/p>","protected":false},"excerpt":{"rendered":"<p>Adattamento: Si prega di controllare il filtro di adattamento automobilistico superiore e la descrizione per vedere se questo articolo funzioner\u00e0 sul vostro veicolo prima dell'acquisto!<br \/>\nNota: filamento singolo C-8 per gli anabbaglianti<br \/>\nPosizione: Lato destro o sinistro<br \/>\nPosizionamento sul veicolo: Sinistra, destra<br \/>\nTipo di lampadina: Tipo di lampadina HB4<\/p>","protected":false},"featured_media":41113,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"inline_featured_image":false,"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[557],"product_tag":[135147],"class_list":{"0":"post-41023","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-car-bulbs","7":"product_tag-warehouse-location-united-states","8":"product_shipping_class-us-stock-flat","9":"pa_brand-siemid","10":"pa_compatibility-2001-chevrolet-silverado","12":"first","13":"instock","14":"sale","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/siemid.com\/it\/wp-json\/wp\/v2\/product\/41023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siemid.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/siemid.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/siemid.com\/it\/wp-json\/wp\/v2\/comments?post=41023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/siemid.com\/it\/wp-json\/wp\/v2\/media\/41113"}],"wp:attachment":[{"href":"https:\/\/siemid.com\/it\/wp-json\/wp\/v2\/media?parent=41023"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/siemid.com\/it\/wp-json\/wp\/v2\/product_brand?post=41023"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/siemid.com\/it\/wp-json\/wp\/v2\/product_cat?post=41023"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/siemid.com\/it\/wp-json\/wp\/v2\/product_tag?post=41023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}